{"id":115,"date":"2024-04-11T01:57:26","date_gmt":"2024-04-11T01:57:26","guid":{"rendered":"https:\/\/apnew2.local\/?page_id=115"},"modified":"2024-05-13T04:43:26","modified_gmt":"2024-05-13T04:43:26","slug":"documents-required","status":"publish","type":"page","link":"https:\/\/aurapay.com\/es\/documents-required\/","title":{"rendered":"Documentos requeridos"},"content":{"rendered":"<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--40);margin-bottom:0;padding-top:0;padding-bottom:0\">\n<h1 class=\"wp-block-heading\">Documentos necesarios para una cuenta<\/h1>\n\n\n\n<p>Para utilizar su cuenta, deber\u00e1 enviar los documentos requeridos a continuaci\u00f3n.<\/p>\n\n\n\n<ul class=\"anchor wp-block-list\">\n<li><a href=\"#personal_account\">Cuenta personal<\/a><\/li>\n\n\n\n<li><a href=\"#business_account\">Cuenta de negocios<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"personal_account\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--30);padding-top:var(--wp--preset--spacing--60)\">Cuenta personal<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-98324f51f223fb64dfe9c02e91b0e4ef\" style=\"margin-top:var(--wp--preset--spacing--30)\">Documentos de verificaci\u00f3n de identidad<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-9e27b96a9e1c04cae473141e2421035e\">Le pediremos que env\u00ede una identificaci\u00f3n con fotograf\u00eda de la persona que registra la cuenta (individual) y una selfie (reconocimiento facial).<\/p>\n\n\n\n<h4 class=\"wp-block-heading icon-id\" style=\"margin-top:var(--wp--preset--spacing--20)\">Verificaci\u00f3n de identidad con foto.<\/h4>\n\n\n\n<p>Presente uno de los siguientes documentos: licencia de conducir, tarjeta My Number (sujeta \u00fanicamente a residentes de Jap\u00f3n) o pasaporte.<\/p>\n\n\n\n<div class=\"wp-block-columns col-border-round is-layout-flex wp-container-core-columns-is-layout-69bbeaac wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column has-border-color has-aurapay-green-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:2px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<h5 class=\"wp-block-heading\">Licencia de conducir<\/h5>\n\n\n\n<p>Por favor env\u00ede el anverso y el reverso de su licencia de conducir.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-aurapay-green-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:2px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<h5 class=\"wp-block-heading\">Pasaporte<\/h5>\n\n\n\n<p>Por favor env\u00ede la p\u00e1gina con su foto y firma.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-aurapay-green-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:2px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<h5 class=\"wp-block-heading\"><strong>Mi tarjeta num\u00e9rica<\/strong><\/h5>\n\n\n\n<p>Por favor env\u00ede el anverso y el reverso de la tarjeta.<br>* Oculte el n\u00famero personal y el c\u00f3digo de barras.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-green-pale-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7b6944f4 wp-block-columns-is-layout-flex\" style=\"border-radius:1rem;margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p>Requisitos<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>Los documentos de identificaci\u00f3n deben ser emitidos por una agencia gubernamental y deben mostrar el mismo nombre y fecha de nacimiento que la informaci\u00f3n registrada en AuraPay.<\/li>\n\n\n\n<li>&nbsp;Un documento de identidad caducado no se puede utilizar como documento de verificaci\u00f3n de identidad.<\/li>\n\n\n\n<li>Tenga en cuenta que la tarjeta de notificaci\u00f3n temporal que le notifica sobre su \u201ctarjeta de mi n\u00famero\u201d personal no se puede utilizar como documento de verificaci\u00f3n de identidad.<\/li>\n\n\n\n<li>Se requiere un pasaporte v\u00e1lido para los ciudadanos japoneses y no japoneses que residen fuera de Jap\u00f3n.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading icon-face\" style=\"margin-top:var(--wp--preset--spacing--20)\">Reconocimiento facial<\/h4>\n\n\n\n<p>Para confirmar que ha enviado su informaci\u00f3n en persona, hemos introducido un procedimiento de reconocimiento facial.<\/p>\n\n\n\n<p class=\"has-small-font-size\">*Aseg\u00farese de seguir los pasos que se muestran en la pantalla. Esto nos permite verificar su identidad en l\u00ednea.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--20)\">Preparaci\u00f3n antes de empezar<\/h5>\n\n\n\n<ul class=\"check wp-block-list\">\n<li>Tenga a mano sus documentos de identificaci\u00f3n con fotograf\u00eda.<\/li>\n\n\n\n<li>Qu\u00edtese cualquier art\u00edculo que le cubra la cara, como m\u00e1scaras, sombreros, gafas de sol y auriculares.<\/li>\n\n\n\n<li>Tome fotograf\u00edas en un entorno bien iluminado.<\/li>\n\n\n\n<li>Prepare un dispositivo con una c\u00e1mara y configure el permiso de acceso para la c\u00e1mara.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">* Si est\u00e1 utilizando un dispositivo sin c\u00e1mara, puede cambiar a un dispositivo m\u00f3vil desde la pantalla para seleccionar el m\u00e9todo de env\u00edo del documento.<\/p>\n\n\n\n<div class=\"wp-block-columns has-green-pale-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7b6944f4 wp-block-columns-is-layout-flex\" style=\"border-radius:1rem;margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p>Requisitos<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>Si est\u00e1 utilizando iOS, utilice el navegador Safari. Si utiliza Android o PC, utilice el navegador Chrome.<\/li>\n\n\n\n<li>Al cambiar de una PC a un dispositivo m\u00f3vil, mantenga abierta la pantalla original de la PC hasta que se complete el procedimiento.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-bc9a3b0b9a401c72cb9991c1c49e6da7\" style=\"margin-top:var(--wp--preset--spacing--30)\">Comprobante de direcci\u00f3n actual<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-a9b69c89a49ae802a19fbc5eef5a0f8c\">Se le pedir\u00e1 que presente uno de los siguientes documentos (dentro de los 3 meses posteriores a la fecha de emisi\u00f3n) que muestren la direcci\u00f3n actual del titular de la cuenta (individuo).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Facturas y recibos de servicios p\u00fablicos.<\/li>\n\n\n\n<li>Extractos y facturas de bancos\/compa\u00f1\u00edas de tarjetas de cr\u00e9dito<\/li>\n\n\n\n<li>Copia del certificado de residencia (Para residentes en Jap\u00f3n)<\/li>\n\n\n\n<li>Certificado de registro de sello (Para residentes en Jap\u00f3n)<\/li>\n\n\n\n<li>Certificado de pago de impuestos (Para residentes en Jap\u00f3n)<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">*Si su n\u00famero personal (Mi N\u00famero) est\u00e1 escrito en los documentos, ocultelo para que no pueda ser visto.<\/p>\n\n\n\n<div class=\"wp-block-columns has-green-pale-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7b6944f4 wp-block-columns-is-layout-flex\" style=\"border-radius:1rem;margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p>Requisitos<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>El nombre y la direcci\u00f3n actual deben coincidir con los datos del solicitante registrados en la cuenta. (Solo son v\u00e1lidos los documentos que tengan impreso el nombre y la direcci\u00f3n actual).<\/li>\n\n\n\n<li>El emisor\/membrete debe estar impreso en el documento.<\/li>\n\n\n\n<li>La fecha de emisi\u00f3n debe imprimirse dentro de los 3 meses posteriores al momento de la aprobaci\u00f3n del documento (env\u00edelo con suficiente antelaci\u00f3n a la fecha l\u00edmite).<\/li>\n\n\n\n<li>Prepare un documento que muestre todos los elementos anteriores en la misma hoja de papel (no se aceptar\u00e1n documentos incompletos).<\/li>\n\n\n\n<li>Los materiales de identificaci\u00f3n (licencia de conducir, tarjeta My Number) no se aceptan como materiales de confirmaci\u00f3n de direcci\u00f3n actual.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"business_account\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--30);padding-top:var(--wp--preset--spacing--60)\">Cuenta de negocios<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-5d4016f5a025a66bfa2aeaf1d297b694\" style=\"margin-top:var(--wp--preset--spacing--30)\">Documentos de verificaci\u00f3n de identidad para representantes.<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-9e27b96a9e1c04cae473141e2421035e\">Le pediremos que env\u00ede una identificaci\u00f3n con fotograf\u00eda de la persona que registra la cuenta (individual) y una selfie (reconocimiento facial).<\/p>\n\n\n\n<h4 class=\"wp-block-heading icon-id\" style=\"margin-top:var(--wp--preset--spacing--20)\">Verificaci\u00f3n de identidad con foto.<\/h4>\n\n\n\n<p>Presente uno de los siguientes documentos: licencia de conducir, tarjeta My Number (sujeta \u00fanicamente a residentes de Jap\u00f3n) o pasaporte.<\/p>\n\n\n\n<div class=\"wp-block-columns col-border-round is-layout-flex wp-container-core-columns-is-layout-69bbeaac wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column has-border-color has-aurapay-green-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:2px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<h5 class=\"wp-block-heading\">Licencia de conducir<\/h5>\n\n\n\n<p>Por favor env\u00ede el anverso y el reverso de su licencia de conducir.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-aurapay-green-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:2px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<h5 class=\"wp-block-heading\">Pasaporte<\/h5>\n\n\n\n<p>Por favor env\u00ede la p\u00e1gina con su foto y firma.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-aurapay-green-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:2px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<h5 class=\"wp-block-heading\">Mi tarjeta num\u00e9rica<\/h5>\n\n\n\n<p>Por favor env\u00ede el anverso y el reverso de la tarjeta.<br>* Oculte el n\u00famero personal y el c\u00f3digo de barras.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-green-pale-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7b6944f4 wp-block-columns-is-layout-flex\" style=\"border-radius:1rem;margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p>Requisitos<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>Los documentos de identificaci\u00f3n deben ser emitidos por una agencia gubernamental y deben mostrar el mismo nombre y fecha de nacimiento que la informaci\u00f3n registrada en AuraPay.<\/li>\n\n\n\n<li>&nbsp;Un documento de identidad caducado no se puede utilizar como documento de verificaci\u00f3n de identidad.<\/li>\n\n\n\n<li>Tenga en cuenta que la tarjeta de notificaci\u00f3n temporal que le notifica sobre su \u201ctarjeta de mi n\u00famero\u201d personal no se puede utilizar como documento de verificaci\u00f3n de identidad.<\/li>\n\n\n\n<li>Se requiere un pasaporte v\u00e1lido para los ciudadanos japoneses y no japoneses que residen fuera de Jap\u00f3n.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading icon-face\" style=\"margin-top:var(--wp--preset--spacing--20)\">Reconocimiento facial<\/h4>\n\n\n\n<p>Para confirmar que ha enviado su informaci\u00f3n en persona, hemos introducido un procedimiento de reconocimiento facial.<\/p>\n\n\n\n<p class=\"has-small-font-size\">*Aseg\u00farese de seguir los pasos que se muestran en la pantalla. Esto nos permite verificar su identidad en l\u00ednea.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Preparaci\u00f3n antes de empezar<\/h5>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tenga a mano sus documentos de identificaci\u00f3n con fotograf\u00eda.<\/li>\n\n\n\n<li>Qu\u00edtese cualquier art\u00edculo que le cubra la cara, como m\u00e1scaras, sombreros, gafas de sol y auriculares.<\/li>\n\n\n\n<li>Tome fotograf\u00edas en un entorno bien iluminado.<\/li>\n\n\n\n<li>Prepare un dispositivo con una c\u00e1mara y configure el permiso de acceso para la c\u00e1mara.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">* Si est\u00e1 utilizando un dispositivo sin c\u00e1mara, puede cambiar a un dispositivo m\u00f3vil desde la pantalla para seleccionar el m\u00e9todo de env\u00edo del documento.<\/p>\n\n\n\n<div class=\"wp-block-columns has-green-pale-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7b6944f4 wp-block-columns-is-layout-flex\" style=\"border-radius:1rem;margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p>Requisitos<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>Si est\u00e1 utilizando iOS, utilice el navegador Safari. Si utiliza Android o PC, utilice el navegador Chrome.<\/li>\n\n\n\n<li>Al cambiar de una PC a un dispositivo m\u00f3vil, mantenga abierta la pantalla original de la PC hasta que se complete el procedimiento.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-3a48448b2c9fdeac3090ea584e5747e6\" style=\"margin-top:var(--wp--preset--spacing--30)\">Comprobante de domicilio actual para representantes<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-a9b69c89a49ae802a19fbc5eef5a0f8c\">Se le pedir\u00e1 que presente uno de los siguientes documentos (dentro de los 3 meses posteriores a la fecha de emisi\u00f3n) que muestren la direcci\u00f3n actual del titular de la cuenta (individuo).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Facturas y recibos de servicios p\u00fablicos.<\/li>\n\n\n\n<li>Extractos y facturas de bancos\/compa\u00f1\u00edas de tarjetas de cr\u00e9dito<\/li>\n\n\n\n<li>Copia del certificado de residencia (Para residentes en Jap\u00f3n)<\/li>\n\n\n\n<li>Certificado de registro de sello (Para residentes en Jap\u00f3n)<\/li>\n\n\n\n<li>Certificado de pago de impuestos (Para residentes en Jap\u00f3n)<\/li>\n<\/ul>\n\n\n\n<p>*Si su n\u00famero personal (Mi N\u00famero) est\u00e1 escrito en los documentos, ocultelo para que no pueda ser visto.<\/p>\n\n\n\n<div class=\"wp-block-columns has-green-pale-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7b6944f4 wp-block-columns-is-layout-flex\" style=\"border-radius:1rem;margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p>Requisitos<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>El nombre y la direcci\u00f3n actual deben coincidir con los datos del solicitante registrados en la cuenta. (Solo son v\u00e1lidos los documentos que tengan impreso el nombre y la direcci\u00f3n actual).<\/li>\n\n\n\n<li>El emisor\/membrete debe estar impreso en el documento.<\/li>\n\n\n\n<li>La fecha de emisi\u00f3n debe imprimirse dentro de los 3 meses posteriores al momento de la aprobaci\u00f3n del documento (env\u00edelo con suficiente antelaci\u00f3n a la fecha l\u00edmite).<\/li>\n\n\n\n<li>Prepare un documento que muestre todos los elementos anteriores en la misma hoja de papel (no se aceptar\u00e1n documentos incompletos).<\/li>\n\n\n\n<li>Los materiales de identificaci\u00f3n (licencia de conducir, tarjeta My Number) no se aceptan como materiales de confirmaci\u00f3n de direcci\u00f3n actual.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-eb4a55bd50110a2706872e0eea52afae\" style=\"margin-top:var(--wp--preset--spacing--30)\">Documentos necesarios para el usuario empresarial<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-1f67617220b6200e5029896664d58f77\">Env\u00ede todos los siguientes documentos del propietario de la billetera (corporaci\u00f3n), que deben indicar su direcci\u00f3n y nombre.<br>Los documentos deben emitirse dentro de los seis meses.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Perfil de trabajo<br>Por favor env\u00ede todas las p\u00e1ginas de los documentos.<br>Tambi\u00e9n puede enviar todas las p\u00e1ginas del contrato social aprobado por las autoridades p\u00fablicas.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">*Tenga en cuenta que es posible que se solicite a los usuarios de diferentes pa\u00edses que carguen otros documentos necesarios para una verificaci\u00f3n adicional. Comun\u00edquese con el equipo de soporte para obtener m\u00e1s informaci\u00f3n.<br>*Por favor env\u00ede datos en formato digital (GIF, JPG, PDF, etc.) que hayan sido escaneados o fotografiados con una c\u00e1mara como un tel\u00e9fono inteligente, sin ning\u00fan trabajo de edici\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-f2c3fc536d491ead5eb29c730ddfa508\" style=\"margin-top:var(--wp--preset--spacing--30)\">Certificado de registro de sello<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-aa9f015cd37b27d113f0008ba4f96e4e\">Env\u00ede los siguientes documentos del propietario de la billetera (corporaci\u00f3n).<br>Los documentos deben emitirse dentro de los 6 meses.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Documentos de confirmaci\u00f3n del sello de la empresa.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">*Por favor env\u00ede datos en formato digital (GIF, JPG, PDF, etc.) que hayan sido escaneados o fotografiados con una c\u00e1mara como un tel\u00e9fono inteligente, sin ning\u00fan trabajo de edici\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-f22a2d0aa3ec84b4a93f5a9a19b16f9c\" style=\"margin-top:var(--wp--preset--spacing--30)\">Prueba de direcci\u00f3n actual de la empresa<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-2262a6335ac1afc483883c2ba434a3f5\">Para una cuenta comercial, deber\u00e1 cargar uno de los documentos a continuaci\u00f3n (el documento debe estar dentro de los 6 meses posteriores a la fecha de emisi\u00f3n).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\">Factura o recibo de servicios p\u00fablicos<br> Factura de Luz, Gas, Agua o NHK<\/li>\n\n\n\n<li>Factura o recibo de impuestos nacionales o locales<\/li>\n\n\n\n<li>Extractos bancarios o de tarjetas de cr\u00e9dito<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">*Por favor env\u00ede datos en formato digital (GIF, JPG, PDF, etc.) que hayan sido escaneados o fotografiados con una c\u00e1mara como un tel\u00e9fono inteligente, sin ning\u00fan trabajo de edici\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-aurapay-green-color has-text-color has-link-color wp-elements-33434f20cdc635eb3098cd0e7f1e33bc\" style=\"margin-top:var(--wp--preset--spacing--30)\">Certificados con sello oficial<\/h3>\n\n\n\n<p class=\"has-aurapay-green-color has-text-color has-link-color wp-elements-2262a6335ac1afc483883c2ba434a3f5\">Para una cuenta comercial, deber\u00e1 cargar uno de los documentos a continuaci\u00f3n (el documento debe estar dentro de los 6 meses posteriores a la fecha de emisi\u00f3n).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\">Certificados con sello oficial<br> <a href=\"https:\/\/aurapay.com\/wp-content\/uploads\/2023\/06\/UBO_Declaration_Form_en_AuraPay.pdf?202306\" target=\"_blank\" rel=\"noreferrer noopener\">Haga clic aqu\u00ed<\/a> para descargar los documentos.<\/li>\n\n\n\n<li>Documentos de identificaci\u00f3n de todos los operadores de cuentas y tomadores de decisiones.<\/li>\n\n\n\n<li>Comprobante de la direcci\u00f3n actual de todos los operadores de cuentas y tomadores de decisiones.<\/li>\n\n\n\n<li>Certificado de sellos registrados para todos los operadores de cuentas y tomadores de decisiones.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">*Por favor env\u00ede datos en formato digital (GIF, JPG, PDF, etc.) que hayan sido escaneados o fotografiados con una c\u00e1mara como un tel\u00e9fono inteligente, sin ning\u00fan trabajo de edici\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-group icon-security has-border-color has-global-padding is-layout-constrained wp-container-core-group-is-layout-578fcd59 wp-block-group-is-layout-constrained\" style=\"border-color:#00A651;border-width:1px;border-radius:1rem;margin-top:var(--wp--preset--spacing--60);padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<p>La informaci\u00f3n proporcionada por los usuarios se cifra con SSL (Secure Sockets Layer) durante el env\u00edo de informaci\u00f3n para salvaguardar todos los datos sensibles.<br>Proteger la informaci\u00f3n de los usuarios contra p\u00e9rdidas, da\u00f1os, fugas y acceso no autorizado, garantizando una plataforma segura para los usuarios.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Documents Required for an Account To use your account, you will need to submit the required documents below. Personal Account Identity verification documents We will ask you to submit a photo identification of the person who register the account (individual) and a selfie (facial recognition). Identity verification with photo Please submit one of the following: driver\u2019s license, My Number card (Subject to Japan residents only) or passport. Driver\u2019s license Please submit the front and back of your driver\u2019s license. Passport Please submit the page with your photo and signature. My Number Card Please submit the front and back of the card.* Please hide the personal number and barcode. Requirements face [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-115","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/pages\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":8,"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/pages\/115\/revisions"}],"predecessor-version":[{"id":978,"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/pages\/115\/revisions\/978"}],"wp:attachment":[{"href":"https:\/\/aurapay.com\/es\/wp-json\/wp\/v2\/media?parent=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}